{"id":5835,"date":"2023-04-30T17:07:20","date_gmt":"2023-04-30T15:07:20","guid":{"rendered":"https:\/\/alara-group.fr\/?p=5835"},"modified":"2023-12-07T14:41:52","modified_gmt":"2023-12-07T13:41:52","slug":"news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup","status":"publish","type":"post","link":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/","title":{"rendered":"[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5835\" class=\"elementor elementor-5835 elementor-5834\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c62b14a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c62b14a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c90580\" data-id=\"3c90580\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b8a972 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b8a972\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f7aa4fb\" data-id=\"f7aa4fb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69fc6f4 elementor-align-left elementor-widget elementor-widget-post-info\" data-id=\"69fc6f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-5eb95cd elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/category\/news-de\/\" class=\"elementor-post-info__terms-list-item\">News<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c948f4 elementor-widget elementor-widget-elementskit-heading\" data-id=\"3c948f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group! <\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c951cd0 elementor-widget elementor-widget-heading\" data-id=\"c951cd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Die Gelegenheit f\u00fcr die Gruppe, ihre Expertise, ihr Engagement und ihre Erfolge zu pr\u00e4sentieren\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-162c638 elementor-widget elementor-widget-text-editor\" data-id=\"162c638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group. Eine Gelegenheit f\u00fcr <\/span><b>unsere Teams kennenlernen,<\/b><span style=\"font-weight: 400;\"> sondern auch <\/span><b>die Fachkenntnisse der Gruppe, ihre Engagements, ihre Erfolge und ihre Entwicklung entdecken.<\/b><span style=\"font-weight: 400;\"> durch mehrere Punkte: <\/span> <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4a66c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2d4a66c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Besch\u00e4ftigung:<\/b> Einstellung von 9 Jugendlichen im Rahmen von #1jeune1solution<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fibermetrix gewinnt den <b>Innovationswettbewerb<\/b> I-Nov im Rahmen des Plans #France2030<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> <b>Entwicklung der Gruppe:<\/b> Besuch des neuen Firmengel\u00e4ndes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9350965 elementor-widget elementor-widget-text-editor\" data-id=\"9350965\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Dieses Treffen bot insbesondere die M\u00f6glichkeit, sich \u00fcber die Entwicklungsperspektiven des Konzerns auszutauschen, der nach den Worten der Pr\u00e4fektin &#8220;an der wirtschaftlichen Dynamik des Niederrheingebiets teilnimmt&#8221;.<\/span><\/p>\n<p><em><strong>Das Alara group Team bedankt sich bei der Pr\u00e4fektin f\u00fcr ihr Kommen und ihr Interesse an der Gruppe!<\/strong><\/em><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e75b27e elementor-widget elementor-widget-text-editor\" data-id=\"e75b27e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Bleib auf dem Laufenden \u00fcber die Neuigkeiten der Gruppe, indem du unsere Linkedin-Seite abonnierst!<br \/><\/span> <span style=\"font-weight: 400;\">\u2794<\/span> <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/bit.ly\/3K34Jgk\">https:\/\/bit.ly\/3K34Jgk<\/a><\/strong><\/span> <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18b0317 elementor-widget elementor-widget-spacer\" data-id=\"18b0317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0956250 elementor-widget elementor-widget-heading\" data-id=\"0956250\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Diesen Artikel teilen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e637a3 elementor-grid-2 elementor-share-buttons--skin-flat elementor-share-buttons--shape-circle elementor-grid-mobile-1 elementor-share-buttons--view-icon-text elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"0e637a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Teilen auf facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tShare on Facebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Teilen auf linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tShare on Linkdin\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e863a5 elementor-widget elementor-widget-spacer\" data-id=\"2e863a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b5c3bd elementor-widget elementor-widget-post-navigation\" data-id=\"6b5c3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Beitrag Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/news-besuch-praesidentin-eurometropole-strassburg-piaimbs\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Zur\u00fcck<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Vorheriger Artikel<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/event-estro2023\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster Artikel<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">N\u00e4chster<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6feb571 elementor-widget elementor-widget-spacer\" data-id=\"6feb571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e14c774 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e14c774\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5639bc3\" data-id=\"5639bc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93790e4 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"93790e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tauschen Sie sich mit uns aus!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-daca183 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"daca183\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-abc6c1c\" data-id=\"abc6c1c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7fa972 elementor-widget elementor-widget-heading\" data-id=\"e7fa972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie sind Arzt?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1294d4b elementor-widget elementor-widget-text-editor\" data-id=\"1294d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bleiben Sie mit unseren kostenlosen Informationen im Bereich Bildgebung und Strahlenschutz immer auf dem Laufenden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b38b97 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"4b38b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alara-group.fr\/de\/kontakt\/?newsletter\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f8afb34\" data-id=\"f8afb34\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b60e57 elementor-widget elementor-widget-heading\" data-id=\"0b60e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie m\u00f6chten Partner werden?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e580422 elementor-widget elementor-widget-text-editor\" data-id=\"e580422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vertrieb, R&amp;D oder klinischer Test?<br \/>Kontaktieren Sie uns!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e95f460 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e95f460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alara-group.fr\/de\/kontakt\/?newsletter\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.<\/p>\n","protected":false},"author":1,"featured_media":4378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-5835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[NEWS] Die Pr\u00e4fektin der Region Grand-Est &amp; des Bas-Rhin bei Alara<\/title>\n<meta name=\"description\" content=\"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[NEWS] Die Pr\u00e4fektin der Region Grand-Est &amp; des Bas-Rhin bei Alara\" \/>\n<meta property=\"og:description\" content=\"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/\" \/>\n<meta property=\"og:site_name\" content=\"Alara group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-30T15:07:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-07T13:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"test\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"test\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/\"},\"author\":{\"name\":\"test\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/person\\\/1967554bf10c69e63fe229d7c5eaa37e\"},\"headline\":\"[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group!\",\"datePublished\":\"2023-04-30T15:07:20+00:00\",\"dateModified\":\"2023-12-07T13:41:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1680187112194.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/\",\"name\":\"[NEWS] Die Pr\u00e4fektin der Region Grand-Est & des Bas-Rhin bei Alara\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1680187112194.jpg\",\"datePublished\":\"2023-04-30T15:07:20+00:00\",\"dateModified\":\"2023-12-07T13:41:52+00:00\",\"description\":\"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1680187112194.jpg\",\"contentUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1680187112194.jpg\",\"width\":2048,\"height\":1153,\"caption\":\"Josiane Chevalier Prefete du Bas Rhin - avec Alara group\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\",\"name\":\"Alara-group\",\"description\":\"Alara group - Toute l&#039;expertise des rayonnements en un seul groupe\",\"publisher\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\"},\"alternateName\":\"Alara group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\",\"name\":\"Alara group\",\"alternateName\":\"Alara group\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Logo_Alaragroup_noir_RVB.png\",\"contentUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Logo_Alaragroup_noir_RVB.png\",\"width\":4069,\"height\":606,\"caption\":\"Alara group\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Alara-group\\\/100064307790593\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alaragroup\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/person\\\/1967554bf10c69e63fe229d7c5eaa37e\",\"name\":\"test\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g\",\"caption\":\"test\"},\"sameAs\":[\"https:\\\/\\\/lab.alara-expertise.fr\"],\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/author\\\/test\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[NEWS] Die Pr\u00e4fektin der Region Grand-Est & des Bas-Rhin bei Alara","description":"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/","og_locale":"de_DE","og_type":"article","og_title":"[NEWS] Die Pr\u00e4fektin der Region Grand-Est & des Bas-Rhin bei Alara","og_description":"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.","og_url":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/","og_site_name":"Alara group","article_publisher":"https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/","article_published_time":"2023-04-30T15:07:20+00:00","article_modified_time":"2023-12-07T13:41:52+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg","type":"image\/jpeg"}],"author":"test","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"test","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#article","isPartOf":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/"},"author":{"name":"test","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/person\/1967554bf10c69e63fe229d7c5eaa37e"},"headline":"[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group!","datePublished":"2023-04-30T15:07:20+00:00","dateModified":"2023-12-07T13:41:52+00:00","mainEntityOfPage":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/"},"wordCount":236,"publisher":{"@id":"https:\/\/alara-group.fr\/de\/#organization"},"image":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#primaryimage"},"thumbnailUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg","articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/","url":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/","name":"[NEWS] Die Pr\u00e4fektin der Region Grand-Est & des Bas-Rhin bei Alara","isPartOf":{"@id":"https:\/\/alara-group.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#primaryimage"},"image":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#primaryimage"},"thumbnailUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg","datePublished":"2023-04-30T15:07:20+00:00","dateModified":"2023-12-07T13:41:52+00:00","description":"Am 29. M\u00e4rz besuchte die Pr\u00e4fektin des Grand Est, Josiane Chevalier, die Alara group.","breadcrumb":{"@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#primaryimage","url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg","contentUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/1680187112194.jpg","width":2048,"height":1153,"caption":"Josiane Chevalier Prefete du Bas Rhin - avec Alara group"},{"@type":"BreadcrumbList","@id":"https:\/\/alara-group.fr\/de\/news-josianechevalier-praefektin-region-grandest-basrhin-zu-besuch-bei-der-alaragroup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alara-group.fr\/de\/"},{"@type":"ListItem","position":2,"name":"[NEWS] Josiane Chevalier Pr\u00e4fektin der Region Grand Est und des Bas-Rhin zu Besuch bei der Alara group!"}]},{"@type":"WebSite","@id":"https:\/\/alara-group.fr\/de\/#website","url":"https:\/\/alara-group.fr\/de\/","name":"Alara-group","description":"Alara group - Toute l&#039;expertise des rayonnements en un seul groupe","publisher":{"@id":"https:\/\/alara-group.fr\/de\/#organization"},"alternateName":"Alara group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alara-group.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/alara-group.fr\/de\/#organization","name":"Alara group","alternateName":"Alara group","url":"https:\/\/alara-group.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/cropped-Logo_Alaragroup_noir_RVB.png","contentUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/cropped-Logo_Alaragroup_noir_RVB.png","width":4069,"height":606,"caption":"Alara group"},"image":{"@id":"https:\/\/alara-group.fr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/","https:\/\/www.linkedin.com\/company\/alaragroup\/"]},{"@type":"Person","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/person\/1967554bf10c69e63fe229d7c5eaa37e","name":"test","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50844b56ab4782de6048b1ddbf7b946ef5ccaaf8584e5630c77ecc7912f687ec?s=96&d=mm&r=g","caption":"test"},"sameAs":["https:\/\/lab.alara-expertise.fr"],"url":"https:\/\/alara-group.fr\/de\/author\/test\/"}]}},"_links":{"self":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/5835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/comments?post=5835"}],"version-history":[{"count":12,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/5835\/revisions"}],"predecessor-version":[{"id":7505,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/5835\/revisions\/7505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/media\/4378"}],"wp:attachment":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/media?parent=5835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/categories?post=5835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/tags?post=5835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}