{"id":9609,"date":"2023-11-28T09:34:04","date_gmt":"2023-11-28T08:34:04","guid":{"rendered":"https:\/\/alara-group.fr\/?p=9609"},"modified":"2024-06-18T14:21:01","modified_gmt":"2024-06-18T12:21:01","slug":"publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet","status":"publish","type":"post","link":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/","title":{"rendered":"[PUBLIKATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9609\" class=\"elementor elementor-9609 elementor-9608\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c62b14a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"c62b14a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-120051a\" data-id=\"120051a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57fa6d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57fa6d5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4aabde6\" data-id=\"4aabde6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed15c5e elementor-align-left elementor-widget elementor-widget-post-info\" data-id=\"ed15c5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-5eb95cd\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/category\/publikation\/\" class=\"elementor-post-info__terms-list-item\">Publikation<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-758c07a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"758c07a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-95647c1\" data-id=\"95647c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e844021 elementor-widget elementor-widget-elementskit-heading\" data-id=\"e844021\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">[PUBLICATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider ekit-dotted\"><div class=\"elementskit-border-divider ekit-dotted\"><\/div><\/div>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Die Zusammenfassung dieser Arbeit, die auf der JFR, der DGMP und der RSNA vorgestellt wurde, finden Sie unten.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cb0f25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cb0f25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-089b3ca\" data-id=\"089b3ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8a7e29 elementor-widget elementor-widget-text-editor\" data-id=\"d8a7e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Einleitung<\/strong>:<\/p>\n<p>CT-Untersuchungen machen 12,8% der im Jahr 2017 durchgef\u00fchrten bildgebenden Untersuchungen aus.<br \/>\nAllerdings entfallen auf diese Untersuchungen mehr als 70% der kollektiven effektiven Dosis.<br \/>\nUm die Exposition der Patienten zu reduzieren, haben die Hersteller mehrere Tools zur Dosisoptimierung eingef\u00fchrt.<br \/>\nZu diesen Techniken geh\u00f6ren die Werkzeuge zum Schutz der Risikoorgane (ODM, OEM, X-CARE), mit denen die Dosis auf der Vorderseite der Patienten reduziert werden kann.<br \/>\nDie einzigen verf\u00fcgbaren Dosisindikatoren (IDSV, PDL) erlauben es jedoch nicht, die Funktionsweise dieser Werkzeuge genau zu untersuchen.<br \/>\nZiel dieser Studie war es, die Relevanz der von den einzelnen Herstellern von Mehrschicht-Scannern angebotenen Tools zum Schutz der Risikoorgane zu bewerten und ihre Auswirkungen auf die Dosimetrie und die Bildqualit\u00e4t bei der Untersuchung des Gehirns abzusch\u00e4tzen.     <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97f2e1f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"97f2e1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1706150\" data-id=\"1706150\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e04f15 elementor-widget elementor-widget-text-editor\" data-id=\"5e04f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Material und Methode<\/strong>:<\/p>\n<p>F\u00fcnf Scannermodelle, die in vier Radiologieabteilungen installiert waren, wurden in dieser <span style=\"letter-spacing: 0.3px;\">Studie<\/span> bewertet : Siemens Somatom Go Top, GE (Revolution CT und Revolution Maxima), Canon (Aquilion <span style=\"letter-spacing: 0.3px;\">Genesis und Aquilion Prime).<br \/>\nAlle Tests wurden mit zwei &#8220;Sch\u00e4del&#8221;-Protokollen durchgef\u00fchrt auf   <\/span><span style=\"letter-spacing: 0.3px;\">ein Phantom vom Typ HEAD16 (Durchmesser 16 cm, PMMA): ein sogenanntes &#8220;Standard&#8221;-Protokoll zum Vergleich  <\/span><span style=\"letter-spacing: 0.3px;\">die Ger\u00e4te untereinander und ein &#8220;klinisches&#8221; Protokoll, das routinem\u00e4\u00dfig verwendet wird.<br \/>\nUm den Gewinn zu quantifizieren   <\/span><span style=\"letter-spacing: 0.3px;\">Dosimetrie, die durch die Werkzeuge zum Schutz der Risikoorgane erzielt wurde, wurde der Szintillationsfaserdetektor <\/span><span style=\"letter-spacing: 0.3px;\">IVInomad auf dem Mylar des Scanners an 16 Messpositionen platziert, die rund um die <\/span> <span style=\"letter-spacing: 0.3px;\">des Rings (siehe Abbildung 1).<br \/>\nDie Bildqualit\u00e4t wurde mit den \u00fcblichen Metriken (SD, RSB, NPS) quantifiziert.   <\/span><span style=\"letter-spacing: 0.3px;\">auf den Bildern des HEAD16-Phantoms, innerhalb von vier paarweise angeordneten Regionen von Interesse  <\/span><span style=\"letter-spacing: 0.3px;\">jeweils auf dem vorderen und hinteren Teil des Phantoms.<br \/>\nEine statistische Analyse wurde   <\/span><span style=\"letter-spacing: 0.3px;\">(Wilcoxon-Test, Blant Altmann) f\u00fcr die Messungen mit und ohne Hilfsmittel zum Schutz des K\u00f6rpers. <\/span><span style=\"letter-spacing: 0.3px;\">Schutz der gef\u00e4hrdeten Organe, um die Signifikanz der Unterschiede in Bezug auf die Qualit\u00e4t zu bewerten. <\/span><span style=\"letter-spacing: 0.3px;\">Bild.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-de97b89\" data-id=\"de97b89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94f459d elementor-widget elementor-widget-image\" data-id=\"94f459d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"743\" height=\"720\" src=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure1-1.jpg\" class=\"attachment-large size-large wp-image-9658\" alt=\"\" srcset=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure1-1.jpg 743w, https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure1-1-300x291.jpg 300w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0ae316 elementor-widget elementor-widget-text-editor\" data-id=\"c0ae316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abbildung 1: Schema des Dosismessungsprotokolls.<br \/>\nDie Punkte stellen die 16 Messpunkte dar, die mit dem IVInomad-Detektor durchgef\u00fchrt wurden. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a7293b elementor-widget elementor-widget-text-editor\" data-id=\"4a7293b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Ergebnisse : <\/b><\/p>\n<p>Wie in Abbildung 2 dargestellt, wird die Dosis auf der Vorderseite des Patienten zwischen  <span style=\"letter-spacing: 0.3px;\">10,9% und 73,8% je nach Protokoll und untersuchtem Scanner.<br \/>\nDie Dosis auf der R\u00fcckseite ist   <\/span><span style=\"letter-spacing: 0.3px;\">unver\u00e4ndert auf den Scannern von GE und Canon.<br \/>\nAllerdings wurde bei Siemens die Dosis auf der R\u00fcckseite   <\/span><span style=\"letter-spacing: 0.3px;\">steigt um etwa 39%.<br \/>\nDas Rauschen (SD), steigt zwischen 2,4 % und 10,4 %, je nach   <\/span><span style=\"letter-spacing: 0.3px;\">Scanner und die untersuchten Regionen.<br \/>\nDies entspricht in absoluten Zahlen einem maximalen Anstieg von 0,5 HU.   <\/span><span style=\"letter-spacing: 0.3px;\">Ebenso sinkt der RSB zwischen 2,6% und 9,6%, was in absoluten Zahlen einen R\u00fcckgang von  <\/span><span style=\"letter-spacing: 0.3px;\">maximal 2,5 HU betragen.<br \/>\nDiese Abweichungen werden als statistisch signifikant angesehen (p-Wert &lt; 0,05).   <\/span><span style=\"letter-spacing: 0.3px;\">Die NPS-Analyse zeigte, dass die Textur des L\u00e4rms nicht beeinflusst wurde.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc2d7c7 elementor-widget elementor-widget-image\" data-id=\"dc2d7c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"950\" height=\"365\" src=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-1-1024x393.jpg\" class=\"attachment-large size-large wp-image-9673\" alt=\"\" srcset=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-1-1024x393.jpg 1024w, https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-1-300x115.jpg 300w, https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-1-768x295.jpg 768w, https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-1.jpg 1280w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4128dde elementor-widget elementor-widget-text-editor\" data-id=\"4128dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abbildung 2: Gemessene Dosisreduktion bei den f\u00fcnf Scans aus: Standardprotokoll.<br \/>\n(a) und dem klinischen Protokoll<br \/>\n(b).<br \/>\nDie gestrichelte Linie stellt einen Nullunterschied zwischen den gemessenen Dosen mit und ohne Schutzvorrichtungen f\u00fcr die gef\u00e4hrdeten Organe dar.<br \/>\n(A): Siemens Somatom Go Top.<br \/>\n(B): GE Revolution CT.<br \/>\n(C): GE Revolution Maxima.<br \/>\n(D): Canon Aquilion Genesis.<br \/>\n(E): Canon Aquilion        <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7be10f elementor-widget elementor-widget-text-editor\" data-id=\"e7be10f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Schlussfolgerung : <\/b><\/p>\n<p>Die verf\u00fcgbaren Werkzeuge zum Schutz von Risikoorganen in der CT reduzieren auf eine Weise  <span style=\"letter-spacing: 0.3px;\">sehr signifikant die Dosis auf der Vorderseite des Patienten.<br \/>\nBei dieser speziellen Studie zu   <\/span><span style=\"letter-spacing: 0.3px;\">bei der Untersuchung des Gehirns reduzieren diese Werkzeuge die Exposition der Vorderseite des Patienten um bis zu  <\/span><span style=\"letter-spacing: 0.3px;\">73,8% je nach Hersteller und verwendetem Protokoll.<br \/>\nAllerdings ist ein Einfluss auf die Bildqualit\u00e4t   <\/span><span style=\"letter-spacing: 0.3px;\">beobachtet mit einem maximalen Anstieg des SD um 0,5 UH und einem R\u00fcckgang des SNR um 2,5 UH am  <\/span><span style=\"letter-spacing: 0.3px;\">maximal. Eine weitere Studie wird f\u00fcr die Untersuchung des Rumpfes durchgef\u00fchrt, um die Auswirkungen dieser Hilfsmittel zu untersuchen  <\/span><span style=\"letter-spacing: 0.3px;\">auf die Exposition des Beckenbereichs und der Brustdr\u00fcsen.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da364f5 elementor-widget elementor-widget-heading\" data-id=\"da364f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Diesen Artikel teilen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1355a2c elementor-grid-2 elementor-share-buttons--skin-flat elementor-share-buttons--shape-circle elementor-grid-mobile-1 elementor-share-buttons--view-icon-text elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"1355a2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Teilen auf facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tShare on Facebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Teilen auf linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tShare on Linkdin\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a963f4c elementor-widget elementor-widget-spacer\" data-id=\"a963f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a46d98 elementor-widget elementor-widget-post-navigation\" data-id=\"7a46d98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Beitrag Navigation\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/event-rosaoktober-jfr2023\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Zur\u00fcck<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Vorheriger Artikel<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/alara-group.fr\/de\/event-dgmp2023\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chster Artikel<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">N\u00e4chster<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd4839 elementor-widget elementor-widget-spacer\" data-id=\"1dd4839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e14c774 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e14c774\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5639bc3\" data-id=\"5639bc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93790e4 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"93790e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tauschen Sie sich mit uns aus!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-daca183 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"daca183\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-abc6c1c\" data-id=\"abc6c1c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7fa972 elementor-widget elementor-widget-heading\" data-id=\"e7fa972\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie sind Arzt?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1294d4b elementor-widget elementor-widget-text-editor\" data-id=\"1294d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bleiben Sie mit unseren kostenlosen Informationen im Bereich Bildgebung und Strahlenschutz immer auf dem Laufenden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b38b97 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"4b38b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alara-group.fr\/de\/kontakt\/?newsletter\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f8afb34\" data-id=\"f8afb34\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b60e57 elementor-widget elementor-widget-heading\" data-id=\"0b60e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie m\u00f6chten Partner werden?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e580422 elementor-widget elementor-widget-text-editor\" data-id=\"e580422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vertrieb, R&amp;D oder klinischer Test?<br \/>Kontaktieren Sie uns!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e95f460 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"e95f460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alara-group.fr\/de\/kontakt\/?newsletter\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abonnieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wissenschaftliche Publikation Fibermetrix: &#8220;Multicentric study of protective tools for organ-to-risk in scanography: radioprotection and image quality&#8221; (Multicenterstudie zum Schutz von Risikoorganen in der CT: Strahlenschutz und Bildqualit\u00e4t).<\/p>\n","protected":false},"author":3,"featured_media":9655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-9609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publikation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality<\/title>\n<meta name=\"description\" content=\"Lesen Sie die Zusammenfassung: &quot;Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality\" \/>\n<meta property=\"og:description\" content=\"Lesen Sie die Zusammenfassung: &quot;Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Alara group\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T08:34:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-18T12:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/\"},\"author\":{\"name\":\"communication\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/person\\\/1101fc0debf281b804f62e69eefa51f7\"},\"headline\":\"[PUBLIKATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t\",\"datePublished\":\"2023-11-28T08:34:04+00:00\",\"dateModified\":\"2024-06-18T12:21:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/\"},\"wordCount\":693,\"publisher\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Figure2-e1698330612683.jpg\",\"articleSection\":[\"Publikation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/\",\"name\":\"[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Figure2-e1698330612683.jpg\",\"datePublished\":\"2023-11-28T08:34:04+00:00\",\"dateModified\":\"2024-06-18T12:21:01+00:00\",\"description\":\"Lesen Sie die Zusammenfassung: \\\"Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Figure2-e1698330612683.jpg\",\"contentUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Figure2-e1698330612683.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[PUBLIKATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\",\"name\":\"Alara-group\",\"description\":\"Alara group - Toute l&#039;expertise des rayonnements en un seul groupe\",\"publisher\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\"},\"alternateName\":\"Alara group\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#organization\",\"name\":\"Alara group\",\"alternateName\":\"Alara group\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Logo_Alaragroup_noir_RVB.png\",\"contentUrl\":\"https:\\\/\\\/alara-group.fr\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-Logo_Alaragroup_noir_RVB.png\",\"width\":4069,\"height\":606,\"caption\":\"Alara group\"},\"image\":{\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Alara-group\\\/100064307790593\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alaragroup\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/#\\\/schema\\\/person\\\/1101fc0debf281b804f62e69eefa51f7\",\"name\":\"communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g\",\"caption\":\"communication\"},\"url\":\"https:\\\/\\\/alara-group.fr\\\/de\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality","description":"Lesen Sie die Zusammenfassung: \"Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/","og_locale":"de_DE","og_type":"article","og_title":"[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality","og_description":"Lesen Sie die Zusammenfassung: \"Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.","og_url":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/","og_site_name":"Alara group","article_publisher":"https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/","article_published_time":"2023-11-28T08:34:04+00:00","article_modified_time":"2024-06-18T12:21:01+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg","type":"image\/jpeg"}],"author":"communication","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"communication","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#article","isPartOf":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/"},"author":{"name":"communication","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/person\/1101fc0debf281b804f62e69eefa51f7"},"headline":"[PUBLIKATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t","datePublished":"2023-11-28T08:34:04+00:00","dateModified":"2024-06-18T12:21:01+00:00","mainEntityOfPage":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/"},"wordCount":693,"publisher":{"@id":"https:\/\/alara-group.fr\/de\/#organization"},"image":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg","articleSection":["Publikation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/","url":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/","name":"[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning[PUBLICATION] Multicenter Study of Organ-to-Risk Protection Tools in Scanning: Radiation Protection and Image Quality","isPartOf":{"@id":"https:\/\/alara-group.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#primaryimage"},"image":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg","datePublished":"2023-11-28T08:34:04+00:00","dateModified":"2024-06-18T12:21:01+00:00","description":"Lesen Sie die Zusammenfassung: \"Multicentric study of the tools to protect organ-to-risk in scanography: radiation protection and image quality.","breadcrumb":{"@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#primaryimage","url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg","contentUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/10\/Figure2-e1698330612683.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/alara-group.fr\/de\/publikation-multicenterstudie-ueber-werkzeuge-zum-schutz-von-risikoorganen-in-der-computertomographie-strahlenschutz-und-bildqualitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alara-group.fr\/de\/"},{"@type":"ListItem","position":2,"name":"[PUBLIKATION] Multicenterstudie \u00fcber Werkzeuge zum Schutz von Risikoorganen in der Computertomographie: Strahlenschutz und Bildqualit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/alara-group.fr\/de\/#website","url":"https:\/\/alara-group.fr\/de\/","name":"Alara-group","description":"Alara group - Toute l&#039;expertise des rayonnements en un seul groupe","publisher":{"@id":"https:\/\/alara-group.fr\/de\/#organization"},"alternateName":"Alara group","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alara-group.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/alara-group.fr\/de\/#organization","name":"Alara group","alternateName":"Alara group","url":"https:\/\/alara-group.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/cropped-Logo_Alaragroup_noir_RVB.png","contentUrl":"https:\/\/alara-group.fr\/wp-content\/uploads\/2023\/03\/cropped-Logo_Alaragroup_noir_RVB.png","width":4069,"height":606,"caption":"Alara group"},"image":{"@id":"https:\/\/alara-group.fr\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Alara-group\/100064307790593\/","https:\/\/www.linkedin.com\/company\/alaragroup\/"]},{"@type":"Person","@id":"https:\/\/alara-group.fr\/de\/#\/schema\/person\/1101fc0debf281b804f62e69eefa51f7","name":"communication","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/49848239d6bb094b91deb074650597864dde1fd541605b51f4a6c11f0e71a673?s=96&d=mm&r=g","caption":"communication"},"url":"https:\/\/alara-group.fr\/de\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/9609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/comments?post=9609"}],"version-history":[{"count":15,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/9609\/revisions"}],"predecessor-version":[{"id":11605,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/posts\/9609\/revisions\/11605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/media\/9655"}],"wp:attachment":[{"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/media?parent=9609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/categories?post=9609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alara-group.fr\/de\/wp-json\/wp\/v2\/tags?post=9609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}